{"id":65,"count":7,"description":"Les Bordures servent \u00e0 la propre s\u00e9paration de deux differentes surfaces ou \u00e0 la stabilisation des bords des pavages, asphalte, du gazon, plates-bandese etc.. La bordure on peut poser a fleur avec les surfaces, l\u00e9g\u00e9rement baisse pour diriger l'eau de la surfaces ou regmont\u00e9e pour donner un ar\u00e9t aux voitures etc.","link":"https:\/\/kaderli.ch\/fr\/categorie-produit\/amenagements-exterieurs-nouvel-creation-etou-reamenagement\/bordures-et-caniveaux\/bordures\/","name":"Bordures","slug":"bordures","taxonomy":"product_cat","parent":41,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/kaderli.ch\/fr\/wp-json\/wp\/v2\/product_cat\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kaderli.ch\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/kaderli.ch\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/kaderli.ch\/fr\/wp-json\/wp\/v2\/product_cat\/41"}],"wp:post_type":[{"href":"https:\/\/kaderli.ch\/fr\/wp-json\/wp\/v2\/product?product_cat=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}